{"id":1314,"date":"2018-09-24T14:16:07","date_gmt":"2018-09-24T12:16:07","guid":{"rendered":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg"},"modified":"2018-09-24T14:16:07","modified_gmt":"2018-09-24T12:16:07","slug":"catalogo-home","status":"inherit","type":"attachment","link":"https:\/\/www.hispabano.es\/es\/hispabano-s-l-fabricante-de-mamparas-de-bano-y-de-ducha\/catalogo-home\/","title":{"rendered":"catalogo-home"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>catalogo-home - Fabricantes de Mamparas de Ba\u00f1o y de Duchas<\/title>\n<meta name=\"description\" content=\"Hispaba\u00f1o, Fabricantes de Mamparas de Ba\u00f1o y de Duchas. catalogo-home. Disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"catalogo-home - Fabricantes de Mamparas de Ba\u00f1o y de Duchas\" \/>\n<meta property=\"og:description\" content=\"Hispaba\u00f1o, Fabricantes de Mamparas de Ba\u00f1o y de Duchas. catalogo-home. Disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/Hispabano\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"820\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg\",\"url\":\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg\",\"name\":\"catalogo-home - Fabricantes de Mamparas de Ba\u00f1o y de Duchas\",\"isPartOf\":{\"@id\":\"https:\/\/www.hispabano.es\/es\/#website\"},\"datePublished\":\"2018-09-24T12:16:07+00:00\",\"dateModified\":\"2018-09-24T12:16:07+00:00\",\"description\":\"Hispaba\u00f1o, Fabricantes de Mamparas de Ba\u00f1o y de Duchas. catalogo-home. Disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.hispabano.es\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicio\",\"item\":\"https:\/\/www.hispabano.es\/es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"catalogo-home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hispabano.es\/es\/#website\",\"url\":\"https:\/\/www.hispabano.es\/es\/\",\"name\":\"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas\",\"description\":\"Como fabricantes, y siguiendo las \u00faltimas tendencias, disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo, para dar respuesta a ...\",\"publisher\":{\"@id\":\"https:\/\/www.hispabano.es\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hispabano.es\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.hispabano.es\/es\/#organization\",\"name\":\"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas\",\"url\":\"https:\/\/www.hispabano.es\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.hispabano.es\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2020\/11\/cropped-favicon.jpg\",\"contentUrl\":\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2020\/11\/cropped-favicon.jpg\",\"width\":512,\"height\":512,\"caption\":\"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas\"},\"image\":{\"@id\":\"https:\/\/www.hispabano.es\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/es-es.facebook.com\/Hispabano\/\",\"https:\/\/www.youtube.com\/@hispabano9335\",\"https:\/\/www.linkedin.com\/company\/hispabao-sl\/mycompany\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"catalogo-home - Fabricantes de Mamparas de Ba\u00f1o y de Duchas","description":"Hispaba\u00f1o, Fabricantes de Mamparas de Ba\u00f1o y de Duchas. catalogo-home. Disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg","og_locale":"es_ES","og_type":"article","og_title":"catalogo-home - Fabricantes de Mamparas de Ba\u00f1o y de Duchas","og_description":"Hispaba\u00f1o, Fabricantes de Mamparas de Ba\u00f1o y de Duchas. catalogo-home. Disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo.","og_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg","og_site_name":"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas","article_publisher":"https:\/\/es-es.facebook.com\/Hispabano\/","og_image":[{"width":820,"height":820,"url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg","url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg","name":"catalogo-home - Fabricantes de Mamparas de Ba\u00f1o y de Duchas","isPartOf":{"@id":"https:\/\/www.hispabano.es\/es\/#website"},"datePublished":"2018-09-24T12:16:07+00:00","dateModified":"2018-09-24T12:16:07+00:00","description":"Hispaba\u00f1o, Fabricantes de Mamparas de Ba\u00f1o y de Duchas. catalogo-home. Disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo.","breadcrumb":{"@id":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hispabano.es\/es\/"},{"@type":"ListItem","position":2,"name":"Inicio","item":"https:\/\/www.hispabano.es\/es\/"},{"@type":"ListItem","position":3,"name":"catalogo-home"}]},{"@type":"WebSite","@id":"https:\/\/www.hispabano.es\/es\/#website","url":"https:\/\/www.hispabano.es\/es\/","name":"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas","description":"Como fabricantes, y siguiendo las \u00faltimas tendencias, disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo, para dar respuesta a ...","publisher":{"@id":"https:\/\/www.hispabano.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hispabano.es\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.hispabano.es\/es\/#organization","name":"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas","url":"https:\/\/www.hispabano.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hispabano.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2020\/11\/cropped-favicon.jpg","contentUrl":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2020\/11\/cropped-favicon.jpg","width":512,"height":512,"caption":"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas"},"image":{"@id":"https:\/\/www.hispabano.es\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/Hispabano\/","https:\/\/www.youtube.com\/@hispabano9335","https:\/\/www.linkedin.com\/company\/hispabao-sl\/mycompany\/"]}]}},"smush":{"stats":{"percent":4.431107308987863,"bytes":3315,"size_before":74812,"size_after":71497,"time":0.13,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"woocommerce_thumbnail":{"percent":4.42,"bytes":807,"size_before":18261,"size_after":17454,"time":0.02},"woocommerce_gallery_thumbnail":{"percent":6.07,"bytes":220,"size_before":3624,"size_after":3404,"time":0.04},"woocommerce_single":{"percent":4.32,"bytes":2288,"size_before":52927,"size_after":50639,"time":0.07}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-300x300.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-300x300.jpg 300w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-100x100.jpg 100w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-600x600.jpg 600w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-150x150.jpg 150w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-768x768.jpg 768w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-48x48.jpg 48w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-250x250.jpg 250w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-550x550.jpg 550w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-800x800.jpg 800w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-180x180.jpg 180w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-500x500.jpg 500w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg 820w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-300x300.jpg 300w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-100x100.jpg 100w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-600x600.jpg 600w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-150x150.jpg 150w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-768x768.jpg 768w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-48x48.jpg 48w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-250x250.jpg 250w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-550x550.jpg 550w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-800x800.jpg 800w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-180x180.jpg 180w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-500x500.jpg 500w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg 820w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":820,"height":820,"file":"2018\/09\/catalogo-home.jpg","sizes":{"woocommerce_thumbnail":{"file":"catalogo-home-300x300.jpg","width":300,"height":300,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"catalogo-home-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-100x100.jpg"},"woocommerce_single":{"file":"catalogo-home-600x600.jpg","width":600,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-600x600.jpg"},"thumbnail":{"file":"catalogo-home-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-150x150.jpg"},"medium":{"file":"catalogo-home-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-300x300.jpg"},"medium_large":{"file":"catalogo-home-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-768x768.jpg"},"shop_thumbnail":{"file":"catalogo-home-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-100x100.jpg"},"shop_catalog":{"file":"catalogo-home-300x300.jpg","width":300,"height":300,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-300x300.jpg"},"shop_single":{"file":"catalogo-home-600x600.jpg","width":600,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-600x600.jpg"},"wcicon":{"file":"catalogo-home-48x48.jpg","width":48,"height":48,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-48x48.jpg"},"wcsquare":{"file":"catalogo-home-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-300x300.jpg"},"wcsmall":{"file":"catalogo-home-250x250.jpg","width":250,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-250x250.jpg"},"wcstandard":{"file":"catalogo-home-550x550.jpg","width":550,"height":550,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-550x550.jpg"},"wcbig":{"file":"catalogo-home-800x800.jpg","width":800,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-800x800.jpg"},"wcfixedheightsmall":{"file":"catalogo-home-180x180.jpg","width":180,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-180x180.jpg"},"wcfixedheightmedium":{"file":"catalogo-home-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-300x300.jpg"},"wcfixedheight":{"file":"catalogo-home-500x500.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-500x500.jpg"},"wccarouselsmall":{"file":"catalogo-home-210x150.jpg","width":210,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-210x150.jpg"},"wccarousel":{"file":"catalogo-home-400x285.jpg","width":400,"height":285,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-400x285.jpg"},"wcslider":{"file":"catalogo-home-800x500.jpg","width":800,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home-800x500.jpg"},"full":{"file":"catalogo-home.jpg","width":820,"height":820,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":7,"source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2018\/09\/catalogo-home.jpg","_links":{"self":[{"href":"https:\/\/www.hispabano.es\/es\/wp-json\/wp\/v2\/media\/1314"}],"collection":[{"href":"https:\/\/www.hispabano.es\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.hispabano.es\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.hispabano.es\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hispabano.es\/es\/wp-json\/wp\/v2\/comments?post=1314"}]}}