{"id":1196,"date":"2016-06-23T12:47:13","date_gmt":"2016-06-23T10:47:13","guid":{"rendered":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg"},"modified":"2016-06-23T12:47:13","modified_gmt":"2016-06-23T10:47:13","slug":"carrusel-553b_deco","status":"inherit","type":"attachment","link":"https:\/\/www.hispabano.es\/es\/hispabano-s-l-fabricante-de-mamparas-de-bano-y-de-ducha\/carrusel-553b_deco\/","title":{"rendered":"carrusel-553b_deco"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>carrusel-553b_deco - Fabricantes de Mamparas de Ba\u00f1o y de Duchas<\/title>\n<meta name=\"description\" content=\"Hispaba\u00f1o, Fabricantes de Mamparas de Ba\u00f1o y de Duchas. carrusel-553b_deco. Disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"carrusel-553b_deco - Fabricantes de Mamparas de Ba\u00f1o y de Duchas\" \/>\n<meta property=\"og:description\" content=\"Hispaba\u00f1o, Fabricantes de Mamparas de Ba\u00f1o y de Duchas. carrusel-553b_deco. Disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/Hispabano\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"322\" \/>\n\t<meta property=\"og:image:height\" content=\"202\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg\",\"url\":\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg\",\"name\":\"carrusel-553b_deco - Fabricantes de Mamparas de Ba\u00f1o y de Duchas\",\"isPartOf\":{\"@id\":\"https:\/\/www.hispabano.es\/es\/#website\"},\"datePublished\":\"2016-06-23T10:47:13+00:00\",\"dateModified\":\"2016-06-23T10:47:13+00:00\",\"description\":\"Hispaba\u00f1o, Fabricantes de Mamparas de Ba\u00f1o y de Duchas. carrusel-553b_deco. Disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.hispabano.es\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicio\",\"item\":\"https:\/\/www.hispabano.es\/es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"carrusel-553b_deco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hispabano.es\/es\/#website\",\"url\":\"https:\/\/www.hispabano.es\/es\/\",\"name\":\"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas\",\"description\":\"Como fabricantes, y siguiendo las \u00faltimas tendencias, disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo, para dar respuesta a ...\",\"publisher\":{\"@id\":\"https:\/\/www.hispabano.es\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hispabano.es\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.hispabano.es\/es\/#organization\",\"name\":\"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas\",\"url\":\"https:\/\/www.hispabano.es\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.hispabano.es\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2020\/11\/cropped-favicon.jpg\",\"contentUrl\":\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2020\/11\/cropped-favicon.jpg\",\"width\":512,\"height\":512,\"caption\":\"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas\"},\"image\":{\"@id\":\"https:\/\/www.hispabano.es\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/es-es.facebook.com\/Hispabano\/\",\"https:\/\/www.youtube.com\/@hispabano9335\",\"https:\/\/www.linkedin.com\/company\/hispabao-sl\/mycompany\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"carrusel-553b_deco - Fabricantes de Mamparas de Ba\u00f1o y de Duchas","description":"Hispaba\u00f1o, Fabricantes de Mamparas de Ba\u00f1o y de Duchas. carrusel-553b_deco. Disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg","og_locale":"es_ES","og_type":"article","og_title":"carrusel-553b_deco - Fabricantes de Mamparas de Ba\u00f1o y de Duchas","og_description":"Hispaba\u00f1o, Fabricantes de Mamparas de Ba\u00f1o y de Duchas. carrusel-553b_deco. Disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo.","og_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg","og_site_name":"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas","article_publisher":"https:\/\/es-es.facebook.com\/Hispabano\/","og_image":[{"width":322,"height":202,"url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg","url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg","name":"carrusel-553b_deco - Fabricantes de Mamparas de Ba\u00f1o y de Duchas","isPartOf":{"@id":"https:\/\/www.hispabano.es\/es\/#website"},"datePublished":"2016-06-23T10:47:13+00:00","dateModified":"2016-06-23T10:47:13+00:00","description":"Hispaba\u00f1o, Fabricantes de Mamparas de Ba\u00f1o y de Duchas. carrusel-553b_deco. Disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo.","breadcrumb":{"@id":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hispabano.es\/es\/"},{"@type":"ListItem","position":2,"name":"Inicio","item":"https:\/\/www.hispabano.es\/es\/"},{"@type":"ListItem","position":3,"name":"carrusel-553b_deco"}]},{"@type":"WebSite","@id":"https:\/\/www.hispabano.es\/es\/#website","url":"https:\/\/www.hispabano.es\/es\/","name":"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas","description":"Como fabricantes, y siguiendo las \u00faltimas tendencias, disponemos de una amplia gama de soluciones, dentro y fuera de nuestro cat\u00e1logo, para dar respuesta a ...","publisher":{"@id":"https:\/\/www.hispabano.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hispabano.es\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.hispabano.es\/es\/#organization","name":"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas","url":"https:\/\/www.hispabano.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hispabano.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2020\/11\/cropped-favicon.jpg","contentUrl":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2020\/11\/cropped-favicon.jpg","width":512,"height":512,"caption":"Hispaba\u00f1o: Fabricante de Mamparas de Ba\u00f1o y de Duchas"},"image":{"@id":"https:\/\/www.hispabano.es\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/Hispabano\/","https:\/\/www.youtube.com\/@hispabano9335","https:\/\/www.linkedin.com\/company\/hispabao-sl\/mycompany\/"]}]}},"smush":{"stats":{"percent":5.347280878435449,"bytes":823,"size_before":15391,"size_after":14568,"time":0.04,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"woocommerce_thumbnail":{"percent":4.92,"bytes":595,"size_before":12090,"size_after":11495,"time":0.02},"woocommerce_gallery_thumbnail":{"percent":6.91,"bytes":228,"size_before":3301,"size_after":3073,"time":0.02}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"188\" data-src=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-300x188.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-300x188.jpg 300w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-250x157.jpg 250w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-287x180.jpg 287w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg 322w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/188;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"188\" src=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-300x188.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-300x188.jpg 300w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-250x157.jpg 250w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-287x180.jpg 287w, https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg 322w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":322,"height":202,"file":"2015\/06\/carrusel-553b_deco.jpg","sizes":{"woocommerce_thumbnail":{"file":"carrusel-553b_deco-300x202.jpg","width":300,"height":202,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-300x202.jpg"},"woocommerce_gallery_thumbnail":{"file":"carrusel-553b_deco-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-100x100.jpg"},"thumbnail":{"file":"carrusel-553b_deco-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-150x150.jpg"},"medium":{"file":"carrusel-553b_deco-300x188.jpg","width":300,"height":188,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-300x188.jpg"},"shop_thumbnail":{"file":"carrusel-553b_deco-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-100x100.jpg"},"shop_catalog":{"file":"carrusel-553b_deco-300x202.jpg","width":300,"height":202,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-300x202.jpg"},"wcicon":{"file":"carrusel-553b_deco-48x48.jpg","width":48,"height":48,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-48x48.jpg"},"wcsquare":{"file":"carrusel-553b_deco-300x202.jpg","width":300,"height":202,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-300x202.jpg"},"wcsmall":{"file":"carrusel-553b_deco-250x157.jpg","width":250,"height":157,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-250x157.jpg"},"wcfixedheightsmall":{"file":"carrusel-553b_deco-287x180.jpg","width":287,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-287x180.jpg"},"wccarouselsmall":{"file":"carrusel-553b_deco-210x150.jpg","width":210,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco-210x150.jpg"},"full":{"file":"carrusel-553b_deco.jpg","width":322,"height":202,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":7,"source_url":"https:\/\/www.hispabano.es\/es\/wp-content\/uploads\/2015\/06\/carrusel-553b_deco.jpg","_links":{"self":[{"href":"https:\/\/www.hispabano.es\/es\/wp-json\/wp\/v2\/media\/1196"}],"collection":[{"href":"https:\/\/www.hispabano.es\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.hispabano.es\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.hispabano.es\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hispabano.es\/es\/wp-json\/wp\/v2\/comments?post=1196"}]}}